{"id":16294,"date":"2016-08-22T10:20:57","date_gmt":"2016-08-22T08:20:57","guid":{"rendered":"https:\/\/www.hair-lounge-meloneras.com\/impressum\/"},"modified":"2021-09-06T10:58:11","modified_gmt":"2021-09-06T08:58:11","slug":"impressum","status":"publish","type":"page","link":"https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"<ol>\n<li>\n<h3>DATOS IDENTIFICATIVOS<\/h3>\n<p>En cumplimiento con el deber de informaci\u00f3n recogido en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, a continuaci\u00f3n se reflejan los siguientes datos: la empresa titular de dominio web es Hair Lounge Melonera (en adelante Sandra Hohner), con domicilio a estos efectos en Avenida Touroperador Vingresor 9, 35100 Maspalomas, de C.I.F.: X4834898E. Correo electr\u00f3nico de contacto: info@hair-lounge-meloneras.com del sitio web.<\/li>\n<li>\n<h3>USUARIOS:<\/h3>\n<p>El acceso y\/o uso de este portal de Sandra Hohner creadora del sitio web atribuye la condici\u00f3n de USUARIO, que acepta, desde dicho acceso y\/o uso, las Condiciones Generales de Uso aqu\u00ed reflejadas.<\/p>\n<p>Las citadas Condiciones ser\u00e1n de aplicaci\u00f3n independientemente de las Condiciones Generales de Contrataci\u00f3n que en su caso resulten de obligado cumplimiento.<\/li>\n<li>\n<h3>USO DEL PORTAL<\/h3>\n<p>El presente portal proporciona el acceso a multitud de informaciones, servicios, programas o datos (en adelante, \u00ablos contenidos\u00bb) en Internet pertenecientes a Sandra Hohner creadora del sitio web o a sus licenciantes a los que el USUARIO pueda tener acceso. El USUARIO asume la responsabilidad del uso del portal. Dicha responsabilidad se extiende al registro que fuese necesario para acceder a determinados servicios o contenidos.<\/p>\n<p>En dicho registro el USUARIO ser\u00e1 responsable de aportar informaci\u00f3n veraz y l\u00edcita. Como consecuencia de este registro, al USUARIO se le puede proporcionar una contrase\u00f1a de la que ser\u00e1 responsable, comprometi\u00e9ndose a hacer un uso diligente y confidencial de la misma. El USUARIO se compromete a hacer un uso adecuado de los contenidos y servicios (como por ejemplo servicios de chat, foros de discusi\u00f3n o grupos de noticias) que Sandra Hohner creadora del sitio web ofrece a trav\u00e9s de su portal y con car\u00e1cter enunciativo pero no limitativo, a no emplearlos para (i) incurrir en actividades il\u00edcitas, ilegales o contrarias a la buena fe y al orden p\u00fablico; (ii) difundir contenidos o propaganda de car\u00e1cter racista, xen\u00f3fobo, pornogr\u00e1fico-ilegal, de apolog\u00eda del terrorismo o atentatorio contra los derechos humanos; (iii) provocar da\u00f1os en los sistemas f\u00edsicos y l\u00f3gicos de Sandra Hohner creadora del sitio web , de sus proveedores o de terceras personas, introducir o difundir en la red virus inform\u00e1ticos o cualesquiera otros sistemas f\u00edsicos o l\u00f3gicos que sean susceptibles de provocar los da\u00f1os anteriormente mencionados; (iv) intentar acceder y, en su caso, utilizar las cuentas de correo electr\u00f3nico de otros usuarios y modificar o manipular sus mensajes. Sandra Hohner creadora del sitio web se reserva el derecho de retirar todos aquellos comentarios y aportaciones que vulneren el respeto a la dignidad de la persona, que sean discriminatorios, xen\u00f3fobos, racistas, pornogr\u00e1ficos, que atenten contra la juventud o la infancia, el orden o la seguridad p\u00fablica o que, a su juicio, no resultaran adecuados para su publicaci\u00f3n. En cualquier caso, Sandra Hohner creadora del sitio web no ser\u00e1 responsable de las opiniones vertidas por los usuarios a trav\u00e9s de los foros, chats, u otras herramientas de participaci\u00f3n.<\/li>\n<li>\n<h3>PROTECCI\u00d3N DE DATOS<\/h3>\n<p>Sandra Hohner creadora del sitio web cumple con las directrices de la Ley Org\u00e1nica 15\/1999 de 13 de diciembre de Protecci\u00f3n de Datos de Car\u00e1cter Personal, el Real Decreto 1720\/2007 de 21 de diciembre por el que se aprueba el Reglamento de desarrollo de la Ley Org\u00e1nica y dem\u00e1s normativa vigente en cada momento, y vela por garantizar un correcto uso y tratamiento de los datos personales del usuario. Para ello, junto a cada formulario de recabo de datos de car\u00e1cter personal, en los servicios que el usuario pueda solicitar a Sandra Hohner creadora del sitio web , har\u00e1 saber al usuario de la existencia y aceptaci\u00f3n de las condiciones particulares del tratamiento de sus datos en cada caso, inform\u00e1ndole de la responsabilidad del fichero creado, la direcci\u00f3n del responsable, la posibilidad de ejercer sus derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n u oposici\u00f3n, la finalidad del tratamiento y las comunicaciones de datos a terceros en su caso.<\/p>\n<p>Asimismo, Sandra Hohner creadora del sitio web informa que da cumplimiento a la Ley 34\/2002 de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico y le solicitar\u00e1 su consentimiento al tratamiento de su correo electr\u00f3nico con fines comerciales en cada momento.<\/li>\n<li>\n<h3>PROPIEDAD INTELECTUAL E INDUSTRIAL<\/h3>\n<p>Sandra Hohner creadora del sitio web por s\u00ed o como cesionaria, es titular de todos los derechos de propiedad intelectual e industrial de su p\u00e1gina web, as\u00ed como de los elementos contenidos en la misma (a t\u00edtulo enunciativo, im\u00e1genes, sonido, audio, v\u00eddeo, software o textos; marcas o logotipos, combinaciones de colores, estructura y dise\u00f1o, selecci\u00f3n de materiales usados, programas de ordenador necesarios para su funcionamiento, acceso y uso, etc.), titularidad de Sandra Hohner creadora del sitio web o bien de sus licenciantes.<\/p>\n<p>Todos los derechos reservados. En virtud de lo dispuesto en los art\u00edculos 8 y 32.1, p\u00e1rrafo segundo, de la Ley de Propiedad Intelectual, quedan expresamente prohibidas la reproducci\u00f3n, la distribuci\u00f3n y la comunicaci\u00f3n p\u00fablica, incluida su modalidad de puesta a disposici\u00f3n, de la totalidad o parte de los contenidos de esta p\u00e1gina web, con fines comerciales, en cualquier soporte y por cualquier medio t\u00e9cnico, sin la autorizaci\u00f3n de Sandra Hohner creadora del sitio web .El USUARIO se compromete a respetar los derechos de Propiedad Intelectual e Industrial titularidad de Sandra Hohner creadora del sitio web. Podr\u00e1 visualizar los elementos del portal e incluso imprimirlos, copiarlos y almacenarlos en el disco duro de su ordenador o en cualquier otro soporte f\u00edsico siempre y cuando sea, \u00fanica y exclusivamente, para su uso personal y privado. El USUARIO deber\u00e1 abstenerse de suprimir, alterar, eludir o manipular cualquier dispositivo de protecci\u00f3n o sistema de seguridad que estuviera instalado en las p\u00e1ginas de Sandra Hohner creadora del sitio web.<\/li>\n<li>\n<h3>EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD<\/h3>\n<p>Sandra Hohner creadora del sitio web. no se hace responsable, en ning\u00fan caso, de los da\u00f1os y perjuicios de cualquier naturaleza que pudieran ocasionar, a t\u00edtulo enunciativo: errores u omisiones en los contenidos, falta de disponibilidad del portal o la transmisi\u00f3n de virus o programas maliciosos o lesivos en los contenidos, a pesar de haber adoptado todas las medidas tecnol\u00f3gicas necesarias para evitarlo.<\/li>\n<li>\n<h3>MODIFICACIONES<\/h3>\n<p>Sandra Hohner creadora del sitio web se reserva el derecho de efectuar sin previo aviso las modificaciones que considere oportunas en su portal, pudiendo cambiar, suprimir o a\u00f1adir tanto los contenidos y servicios que se presten a trav\u00e9s de la misma como la forma en la que \u00e9stos aparezcan presentados o localizados en su portal.<\/li>\n<li>\n<h3>ENLACES<\/h3>\n<p>En el caso de que en nombre del dominio se dispusiesen enlaces o hiperv\u00ednculos hac\u00eda otros sitios de Internet, Sandra Hohner creadora del sitio web no ejercer\u00e1 ning\u00fan tipo de control sobre dichos sitios y contenidos. En ning\u00fan caso Sandra Hohner creadora del sitio web asumir\u00e1 responsabilidad alguna por los contenidos de alg\u00fan enlace perteneciente a un sitio web ajeno, ni garantizar\u00e1 la disponibilidad t\u00e9cnica, calidad, fiabilidad, exactitud, amplitud, veracidad, validez y constitucionalidad de cualquier material o informaci\u00f3n contenida en ninguno de dichos hiperv\u00ednculos u otros sitios de Internet.<\/p>\n<p>Igualmente la inclusi\u00f3n de estas conexiones externas no implicar\u00e1 ning\u00fan tipo de asociaci\u00f3n, fusi\u00f3n o participaci\u00f3n con las entidades conectadas.<\/li>\n<li>\n<h3>DERECHO DE EXCLUSI\u00d3N<\/h3>\n<p>Sandra Hohner creadora del sitio web se reserva el derecho a denegar o retirar el acceso a portal y\/o los servicios ofrecidos sin necesidad de preaviso, a instancia propia o de un tercero, a aquellos usuarios que incumplan las presentes Condiciones Generales de Uso.<\/li>\n<li>\n<h3>GENERALIDADES<\/h3>\n<p>Sandra Hohner creadora del sitio web perseguir\u00e1 el incumplimiento de las presentes condiciones as\u00ed como cualquier utilizaci\u00f3n indebida de su portal ejerciendo todas las acciones civiles y penales que le puedan corresponder en derecho.<\/li>\n<li>\n<h3>MODIFICACI\u00d3N DE LAS PRESENTES CONDICIONES Y DURACI\u00d3N<\/h3>\n<p>Sandra Hohner creadora del sitio web podr\u00e1 modificar en cualquier momento las condiciones aqu\u00ed determinadas, siendo debidamente publicadas como aqu\u00ed aparecen. La vigencia de las citadas condiciones ir\u00e1 en funci\u00f3n de su exposici\u00f3n y estar\u00e1n vigentes hasta que sean modificadas por otras debidamente publicadas.<\/li>\n<li>\n<h3>LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/h3>\n<p>La relaci\u00f3n entre Sandra Hohner creadora del sitio web y el USUARIO se regir\u00e1 por la normativa espa\u00f1ola vigente y cualquier controversia se someter\u00e1 a los Juzgados y tribunales.<\/li>\n<\/ol>\n<div class=\"shariff\"><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#1e3050\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.hair-lounge-meloneras.com%2Fes%2Fimpressum%2F&text=Aviso%20legal\" title=\"Compartir en X (Twitter)\" aria-label=\"Compartir en X (Twitter)\" role=\"button\" rel=\"noreferrernoopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"1em\" viewBox=\"0 0 512 512\"><!--! Font Awesome Free 6.4.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license (Commercial License) Copyright 2023 Fonticons, Inc. --><style>svg{fill:#ffffff}<\/style><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"\/><\/svg><\/span><span class=\"shariff-text\">tweet<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.hair-lounge-meloneras.com%2Fes%2Fimpressum%2F\" title=\"Compartir en Facebook\" aria-label=\"Compartir en Facebook\" role=\"button\" rel=\"noreferrernoopener nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\">compartir<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Fwww.hair-lounge-meloneras.com%2Fes%2Fimpressum%2F%20Aviso%20legal\" title=\"Compartir en Whatsapp\" aria-label=\"Compartir en Whatsapp\" role=\"button\" rel=\"noreferrernoopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><span class=\"shariff-text\">compartir<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button printer shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"javascript:window.print()\" title=\"imprimir\" aria-label=\"imprimir\" role=\"button\" rel=\"noreferrernoopener nofollow\" class=\"shariff-link\" style=\"; background-color:#999; color:#fff\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 30 32\"><path fill=\"#999\" d=\"M6.8 27.4h16v-4.6h-16v4.6zM6.8 16h16v-6.8h-2.8q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-11.4v11.4zM27.4 17.2q0-0.5-0.3-0.8t-0.8-0.4-0.8 0.4-0.3 0.8 0.3 0.8 0.8 0.3 0.8-0.3 0.3-0.8zM29.7 17.2v7.4q0 0.2-0.2 0.4t-0.4 0.2h-4v2.8q0 0.7-0.5 1.2t-1.2 0.5h-17.2q-0.7 0-1.2-0.5t-0.5-1.2v-2.8h-4q-0.2 0-0.4-0.2t-0.2-0.4v-7.4q0-1.4 1-2.4t2.4-1h1.2v-9.7q0-0.7 0.5-1.2t1.2-0.5h12q0.7 0 1.6 0.4t1.3 0.8l2.7 2.7q0.5 0.5 0.9 1.4t0.4 1.6v4.6h1.1q1.4 0 2.4 1t1 2.4z\"\/><\/svg><\/span><span class=\"shariff-text\">imprimir<\/span>&nbsp;<\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>DATOS IDENTIFICATIVOS En cumplimiento con el deber de informaci\u00f3n recogido en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, a continuaci\u00f3n se reflejan los siguientes datos: la empresa titular de dominio&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16294","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso legal - Beauty-Lounge-Maspalomas by Sandra Hohner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal - Beauty-Lounge-Maspalomas by Sandra Hohner\" \/>\n<meta property=\"og:description\" content=\"DATOS IDENTIFICATIVOS En cumplimiento con el deber de informaci\u00f3n recogido en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, a continuaci\u00f3n se reflejan los siguientes datos: la empresa titular de dominio...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"Beauty-Lounge-Maspalomas by Sandra Hohner\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-06T08:58:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/impressum\\\/\",\"url\":\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/impressum\\\/\",\"name\":\"Aviso legal - Beauty-Lounge-Maspalomas by Sandra Hohner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/#website\"},\"datePublished\":\"2016-08-22T08:20:57+00:00\",\"dateModified\":\"2021-09-06T08:58:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/impressum\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/impressum\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/impressum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/\",\"name\":\"Beauty-Lounge-Maspalomas by Sandra Hohner\",\"description\":\"YOUR BEAUTY IS OUR MISSION\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hair-lounge-meloneras.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso legal - Beauty-Lounge-Maspalomas by Sandra Hohner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/","og_locale":"es_ES","og_type":"article","og_title":"Aviso legal - Beauty-Lounge-Maspalomas by Sandra Hohner","og_description":"DATOS IDENTIFICATIVOS En cumplimiento con el deber de informaci\u00f3n recogido en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, a continuaci\u00f3n se reflejan los siguientes datos: la empresa titular de dominio...","og_url":"https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/","og_site_name":"Beauty-Lounge-Maspalomas by Sandra Hohner","article_modified_time":"2021-09-06T08:58:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/","url":"https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/","name":"Aviso legal - Beauty-Lounge-Maspalomas by Sandra Hohner","isPartOf":{"@id":"https:\/\/www.hair-lounge-meloneras.com\/es\/#website"},"datePublished":"2016-08-22T08:20:57+00:00","dateModified":"2021-09-06T08:58:11+00:00","breadcrumb":{"@id":"https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hair-lounge-meloneras.com\/es\/impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hair-lounge-meloneras.com\/es\/"},{"@type":"ListItem","position":2,"name":"Aviso legal"}]},{"@type":"WebSite","@id":"https:\/\/www.hair-lounge-meloneras.com\/es\/#website","url":"https:\/\/www.hair-lounge-meloneras.com\/es\/","name":"Beauty-Lounge-Maspalomas by Sandra Hohner","description":"YOUR BEAUTY IS OUR MISSION","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hair-lounge-meloneras.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.hair-lounge-meloneras.com\/es\/wp-json\/wp\/v2\/pages\/16294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hair-lounge-meloneras.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hair-lounge-meloneras.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hair-lounge-meloneras.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hair-lounge-meloneras.com\/es\/wp-json\/wp\/v2\/comments?post=16294"}],"version-history":[{"count":4,"href":"https:\/\/www.hair-lounge-meloneras.com\/es\/wp-json\/wp\/v2\/pages\/16294\/revisions"}],"predecessor-version":[{"id":16511,"href":"https:\/\/www.hair-lounge-meloneras.com\/es\/wp-json\/wp\/v2\/pages\/16294\/revisions\/16511"}],"wp:attachment":[{"href":"https:\/\/www.hair-lounge-meloneras.com\/es\/wp-json\/wp\/v2\/media?parent=16294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}